{"id":154,"date":"2023-03-12T19:24:22","date_gmt":"2023-03-12T19:24:22","guid":{"rendered":"https:\/\/agrilasa.co.za\/members_wp?page_id=154"},"modified":"2025-08-27T15:42:45","modified_gmt":"2025-08-27T13:42:45","slug":"event-registration-form","status":"publish","type":"page","link":"https:\/\/agrilasa.co.za\/members_wp\/event-registration-form\/","title":{"rendered":"Event Registration Form"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][wpforms_selector form_id=&#8221;592&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/wpforms_selector][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"et_pb_module wpforms_selector wpforms_selector_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-592\">\n\t\t\t\t#wpforms-592 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-592\"><form id=\"wpforms-form-592\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"592\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/members_wp\/wp-json\/wp\/v2\/pages\/154\" data-token=\"04cda763b3eaef8cd40f38ca4890565a\" data-token-time=\"1778700030\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-592-field_1-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Registration Type <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-592-field_1\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-592-field_1_1\" name=\"wpforms[fields][1]\" value=\"Annual General Meeting\" aria-errormessage=\"wpforms-592-field_1_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-592-field_1_1\">Annual General Meeting<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-592-field_1_2\" name=\"wpforms[fields][1]\" value=\"Conference\" aria-errormessage=\"wpforms-592-field_1_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-592-field_1_2\">Conference<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-592-field_1_3\" name=\"wpforms[fields][1]\" value=\"Workshop\" aria-errormessage=\"wpforms-592-field_1_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-592-field_1_3\">Workshop<\/label><\/li><\/ul><\/fieldset><\/div>\t\t<div id=\"wpforms-592-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-592-field_4\" >Contact Laboratory Requirements<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-592-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-592-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-592-field_2\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][2][first]\" aria-errormessage=\"wpforms-592-field_2-error\" required><label for=\"wpforms-592-field_2\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-592-field_2-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][2][last]\" aria-errormessage=\"wpforms-592-field_2-last-error\" required><label for=\"wpforms-592-field_2-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-592-field_3-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-592-field_3\">Laboratory Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-592-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-592-field_3-error\" required><\/div><div id=\"wpforms-592-field_5-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-592-field_5\">Contact Number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-592-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" step=\"any\" aria-errormessage=\"wpforms-592-field_5-error\" required><\/div><div id=\"wpforms-592-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-592-field_6\">Email Address <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-592-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" spellcheck=\"false\" aria-errormessage=\"wpforms-592-field_6-error\" required><\/div><div id=\"wpforms-592-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-592-field_8\">Dietary Requirements<\/label><input type=\"text\" id=\"wpforms-592-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-592-field_8-error\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-592-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-592-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-592-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"592\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/pages\/154\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-592\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/agrilasa.co.za\/members_wp\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:kadence\/form {\"uniqueID\":\"154_b13731-d0\",\"postID\":\"154\",\"fields\":[{\"label\":\"Registration Type\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"rows\":4,\"options\":[{\"value\":\"Annual General Meeting\",\"label\":\"Annual General Meeting\"},{\"value\":\"Conference\",\"label\":\"Conference\"},{\"value\":\"Workshop\",\"label\":\"Workshop\"},{\"value\":\"Sponsor an Event\",\"label\":\"Sponsor an Event\"}],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"radio\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\"},{\"label\":\"Full Name\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"description\":\"\",\"rows\":4,\"options\":[{\"value\":\"\",\"label\":\"\"}],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"text\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\",\"slug\":\"\",\"ariaLabel\":\"\"},{\"label\":\"Laboratory Name\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"rows\":4,\"options\":[],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"text\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\"},{\"label\":\"Contact Number\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"rows\":4,\"options\":[],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"text\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\"},{\"label\":\"Email Address\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"description\":\"\",\"rows\":4,\"options\":[{\"value\":\"\",\"label\":\"\"}],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"email\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\",\"slug\":\"\",\"ariaLabel\":\"\"},{\"label\":\"I will be attend the Conference\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"rows\":4,\"options\":[{\"value\":\"in person\",\"label\":\"in person\"},{\"value\":\"online\",\"label\":\"online\"}],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"radio\",\"required\":true,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\"},{\"label\":\"Comments\",\"showLabel\":true,\"placeholder\":\"\",\"default\":\"\",\"description\":\"\",\"rows\":4,\"options\":[{\"value\":\"\",\"label\":\"\"}],\"multiSelect\":false,\"inline\":false,\"showLink\":false,\"min\":\"\",\"max\":\"\",\"type\":\"textarea\",\"required\":false,\"width\":[\"100\",\"\",\"\"],\"auto\":\"\",\"errorMessage\":\"\",\"requiredMessage\":\"\",\"slug\":\"\",\"ariaLabel\":\"\"}],\"messages\":[{\"success\":\"Registration successful.  See you at the event.\",\"error\":\"Registration failed.  Please try again later.\",\"required\":\"\",\"invalid\":\"\",\"recaptchaerror\":\"\",\"preError\":\"\"}],\"email\":[{\"emailTo\":\"info@agrilasa.co.za\",\"subject\":\"Event Registration\",\"fromEmail\":\"noreply@agrilasa.co.za\",\"fromName\":\"Agrilasa\",\"replyTo\":\"from_email\",\"cc\":\"\",\"bcc\":\"\",\"html\":true}]} -->\n<div class=\"wp-block-kadence-form kadence-form-154_b13731-d0 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_0\">Registration Type<span class=\"required\">*<\/span><\/label><div data-type=\"radio\" data-label=\"Registration Type\" id=\"kb_field_154_b13731-d0_0\" class=\"kb-field kb-radio-style-field kb-radio-field kb-field-0 kb-radio-style-normal\" data-required=\"yes\"><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-0\"><input type=\"radio\" name=\"kb_field_0[]\" id=\"kb_field_0_0\" class=\"kb-sub-field kb-radio-style\" value=\"Annual General Meeting\"\/><label for=\"kb_field_0_0\">Annual General Meeting<\/label><\/div><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-1\"><input type=\"radio\" name=\"kb_field_0[]\" id=\"kb_field_0_1\" class=\"kb-sub-field kb-radio-style\" value=\"Conference\"\/><label for=\"kb_field_0_1\">Conference<\/label><\/div><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-2\"><input type=\"radio\" name=\"kb_field_0[]\" id=\"kb_field_0_2\" class=\"kb-sub-field kb-radio-style\" value=\"Workshop\"\/><label for=\"kb_field_0_2\">Workshop<\/label><\/div><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-3\"><input type=\"radio\" name=\"kb_field_0[]\" id=\"kb_field_0_3\" class=\"kb-sub-field kb-radio-style\" value=\"Sponsor an Event\"\/><label for=\"kb_field_0_3\">Sponsor an Event<\/label><\/div><\/div><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_1\">Full Name<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_154_b13731-d0_1\" data-label=\"Full Name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_2\">Laboratory Name<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_154_b13731-d0_2\" data-label=\"Laboratory Name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_3\">Contact Number<span class=\"required\">*<\/span><\/label><input name=\"kb_field_3\" id=\"kb_field_154_b13731-d0_3\" data-label=\"Contact Number\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_4\">Email Address<span class=\"required\">*<\/span><\/label><input name=\"kb_field_4\" id=\"kb_field_154_b13731-d0_4\" data-label=\"Email Address\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-4\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-5 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_5\">I will be attend the Conference<span class=\"required\">*<\/span><\/label><div data-type=\"radio\" data-label=\"I will be attend the Conference\" id=\"kb_field_154_b13731-d0_5\" class=\"kb-field kb-radio-style-field kb-radio-field kb-field-5 kb-radio-style-normal\" data-required=\"yes\"><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-0\"><input type=\"radio\" name=\"kb_field_5[]\" id=\"kb_field_5_0\" class=\"kb-sub-field kb-radio-style\" value=\"in person\"\/><label for=\"kb_field_5_0\">in person<\/label><\/div><div data-type=\"radio\" class=\"kb-radio-item kb-radio-item-1\"><input type=\"radio\" name=\"kb_field_5[]\" id=\"kb_field_5_1\" class=\"kb-sub-field kb-radio-style\" value=\"online\"\/><label for=\"kb_field_5_1\">online<\/label><\/div><\/div><\/div><div class=\"kadence-blocks-form-field kb-form-field-6 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_154_b13731-d0_6\">Comments<\/label><textarea name=\"kb_field_6\" id=\"kb_field_154_b13731-d0_6\" data-label=\"Comments\" type=\"textarea\" placeholder=\"\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-6\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"154_b13731-d0\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"154\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"off\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\"\/><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<!-- \/wp:kadence\/form -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-154","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/pages\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/comments?post=154"}],"version-history":[{"count":17,"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/pages\/154\/revisions"}],"predecessor-version":[{"id":619,"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/pages\/154\/revisions\/619"}],"wp:attachment":[{"href":"https:\/\/agrilasa.co.za\/members_wp\/wp-json\/wp\/v2\/media?parent=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}